{"id":12322,"date":"2025-01-08T23:17:00","date_gmt":"2025-01-08T23:17:00","guid":{"rendered":"https:\/\/ptt2.go.th\/home\/?p=12322"},"modified":"2025-01-09T02:01:50","modified_gmt":"2025-01-09T02:01:50","slug":"%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8","status":"publish","type":"post","link":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/","title":{"rendered":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32"},"content":{"rendered":"\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 13.30 \u0e19. \u0e14\u0e23.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e2d\u0e48\u0e27\u0e21 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e1e\u0e34\u0e0a\u0e2a\u0e34\u0e23\u0e34 \u0e16\u0e34\u0e23\u0e27\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e07\u0e28\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 8 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23\u0e18\u0e23\u0e23\u0e21\u0e32\u0e23\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1e\u0e2a\u0e01\u0e19\u0e34\u0e01\u0e23\u0e17\u0e38\u0e01\u0e2b\u0e21\u0e39\u0e48\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e16\u0e27\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25 \u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e07\u0e23\u0e31\u0e01\u0e20\u0e31\u0e01\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e19\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e33\u0e2a\u0e2d\u0e19\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FPathumthani2%2Fposts%2Fpfbid0d37nWnAHjqU6a4pQzuvhiSYKdJrD48pGuA4i8eC9XHJrmp4sEX9bDQDrZRVTA2oVl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"800\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 13.30 \u0e19. \u0e14\u0e23.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e2d [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":12325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-12322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptt2.go.th\/home\/\u0e23\u0e2d\u0e07\u0e1c\u0e2d-\u0e2a\u0e1e\u0e1b-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35-\u0e40\u0e02\u0e15-2-\u0e23\u0e48-8\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 13.30 \u0e19. \u0e14\u0e23.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e2d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptt2.go.th\/home\/\u0e23\u0e2d\u0e07\u0e1c\u0e2d-\u0e2a\u0e1e\u0e1b-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35-\u0e40\u0e02\u0e15-2-\u0e23\u0e48-8\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/PathumthaniArea2\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-08T23:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-09T02:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"834\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/\"},\"author\":{\"name\":\"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/decb3dc594edbbff02735acfb5cddab7\"},\"headline\":\"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32\",\"datePublished\":\"2025-01-08T23:17:00+00:00\",\"dateModified\":\"2025-01-09T02:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/#organization\"},\"image\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/\",\"url\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/\",\"name\":\"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\",\"isPartOf\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg\",\"datePublished\":\"2025-01-08T23:17:00+00:00\",\"dateModified\":\"2025-01-09T02:01:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage\",\"url\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg\",\"contentUrl\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg\",\"width\":834,\"height\":677},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ptt2.go.th\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#website\",\"url\":\"https:\/\/ptt2.go.th\/home\/\",\"name\":\"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\",\"publisher\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ptt2.go.th\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#organization\",\"name\":\"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\",\"url\":\"https:\/\/ptt2.go.th\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2023\/05\/\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27-\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25-\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a-\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27-\u0e42\u0e25\u0e42\u0e01\u0e49-.png\",\"contentUrl\":\"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2023\/05\/\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27-\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25-\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a-\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27-\u0e42\u0e25\u0e42\u0e01\u0e49-.png\",\"width\":346,\"height\":387,\"caption\":\"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2\"},\"image\":{\"@id\":\"https:\/\/ptt2.go.th\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/PathumthaniArea2\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/decb3dc594edbbff02735acfb5cddab7\",\"name\":\"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/28abdbc7f94d5f6c5fc4e4c4cffbc7dc3addb8af4cc1d26ad88bc3f4d8c5a3b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/28abdbc7f94d5f6c5fc4e4c4cffbc7dc3addb8af4cc1d26ad88bc3f4d8c5a3b2?s=96&d=mm&r=g\",\"caption\":\"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\"},\"url\":\"https:\/\/ptt2.go.th\/home\/author\/sirigunya\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptt2.go.th\/home\/\u0e23\u0e2d\u0e07\u0e1c\u0e2d-\u0e2a\u0e1e\u0e1b-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35-\u0e40\u0e02\u0e15-2-\u0e23\u0e48-8\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 13.30 \u0e19. \u0e14\u0e23.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e2d [&hellip;]","og_url":"https:\/\/ptt2.go.th\/home\/\u0e23\u0e2d\u0e07\u0e1c\u0e2d-\u0e2a\u0e1e\u0e1b-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35-\u0e40\u0e02\u0e15-2-\u0e23\u0e48-8\/","og_site_name":"\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","article_publisher":"https:\/\/web.facebook.com\/PathumthaniArea2\/","article_published_time":"2025-01-08T23:17:00+00:00","article_modified_time":"2025-01-09T02:01:50+00:00","og_image":[{"width":834,"height":677,"url":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg","type":"image\/jpeg"}],"author":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#article","isPartOf":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/"},"author":{"name":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","@id":"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/decb3dc594edbbff02735acfb5cddab7"},"headline":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32","datePublished":"2025-01-08T23:17:00+00:00","dateModified":"2025-01-09T02:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/"},"wordCount":0,"publisher":{"@id":"https:\/\/ptt2.go.th\/home\/#organization"},"image":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage"},"thumbnailUrl":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/","url":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/","name":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32 | \u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","isPartOf":{"@id":"https:\/\/ptt2.go.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage"},"image":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage"},"thumbnailUrl":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg","datePublished":"2025-01-08T23:17:00+00:00","dateModified":"2025-01-09T02:01:50+00:00","breadcrumb":{"@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#primaryimage","url":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg","contentUrl":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-e1736388094590.jpg","width":834,"height":677},{"@type":"BreadcrumbList","@id":"https:\/\/ptt2.go.th\/home\/%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%b5-%e0%b9%80%e0%b8%82%e0%b8%95-2-%e0%b8%a3%e0%b9%88-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptt2.go.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e2d\u0e07\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e25\u0e39\u0e01\u0e40\u0e18\u0e2d \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e13\u0e13\u0e27\u0e23\u0e35 \u0e19\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e0d\u0e0d\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/ptt2.go.th\/home\/#website","url":"https:\/\/ptt2.go.th\/home\/","name":"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","publisher":{"@id":"https:\/\/ptt2.go.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptt2.go.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/ptt2.go.th\/home\/#organization","name":"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2","url":"https:\/\/ptt2.go.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/ptt2.go.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2023\/05\/\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27-\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25-\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a-\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27-\u0e42\u0e25\u0e42\u0e01\u0e49-.png","contentUrl":"https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2023\/05\/\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27-\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25-\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a-\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27-\u0e42\u0e25\u0e42\u0e01\u0e49-.png","width":346,"height":387,"caption":"\u0e2a\u0e1e\u0e1b \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2"},"image":{"@id":"https:\/\/ptt2.go.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/PathumthaniArea2\/"]},{"@type":"Person","@id":"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/decb3dc594edbbff02735acfb5cddab7","name":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/ptt2.go.th\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/28abdbc7f94d5f6c5fc4e4c4cffbc7dc3addb8af4cc1d26ad88bc3f4d8c5a3b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28abdbc7f94d5f6c5fc4e4c4cffbc7dc3addb8af4cc1d26ad88bc3f4d8c5a3b2?s=96&d=mm&r=g","caption":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"},"url":"https:\/\/ptt2.go.th\/home\/author\/sirigunya\/"}]}},"featured_image_src_large":["https:\/\/ptt2.go.th\/home\/wp-content\/uploads\/2025\/01\/472763123_122152140080354597_5850374921017603694_n-1024x944.jpg",750,691,true],"author_info":{"display_name":"\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","author_link":"https:\/\/ptt2.go.th\/home\/author\/sirigunya\/"},"comment_info":0,"category_info":[{"term_id":3,"name":"\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15","slug":"news","term_group":0,"term_taxonomy_id":3,"taxonomy":"category","description":"","parent":0,"count":1202,"filter":"raw","cat_ID":3,"category_count":1202,"category_description":"","cat_name":"\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15","category_nicename":"news","category_parent":0}],"tag_info":false,"taxonomy_info":{"category":[{"value":3,"label":"\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15"}]},"acf":[],"_links":{"self":[{"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/posts\/12322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/comments?post=12322"}],"version-history":[{"count":1,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/posts\/12322\/revisions"}],"predecessor-version":[{"id":12323,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/posts\/12322\/revisions\/12323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/media\/12325"}],"wp:attachment":[{"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/media?parent=12322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/categories?post=12322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptt2.go.th\/home\/wp-json\/wp\/v2\/tags?post=12322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}